{"id":4229,"date":"2024-06-12T11:00:38","date_gmt":"2024-06-12T16:00:38","guid":{"rendered":"https:\/\/texsalvenezuela.com\/tienda\/?post_type=product&#038;p=4229"},"modified":"2025-09-11T14:56:57","modified_gmt":"2025-09-11T18:56:57","slug":"sonax-extreme-detailer-brillo-750ml","status":"publish","type":"product","link":"https:\/\/texsalvenezuela.com\/tienda\/producto\/sonax-extreme-detailer-brillo-750ml\/","title":{"rendered":"Sonax Extreme Detailer Brillo 750ml"},"content":{"rendered":"<p>* El cuidado r\u00e1pido de la pintura para entremedias.<br \/>\n* Limpia de manera protectora y a fondo las superficies ligeramente sucias sin rayarlas<br \/>\n* Mejora el acabado de la pintura y le proporciona una superficie suave y lisa y un brillo intenso brillante<br \/>\n* Renueva los tratamientos de cera existentes y deja un efecto adicional repelente al agua<\/p>\n","protected":false},"excerpt":{"rendered":"<p>* El cuidado r\u00e1pido de la pintura para entremedias. * Limpia de manera protectora y a fondo las superficies ligeramente sucias sin rayarlas * Mejora el acabado de la pintura y le proporciona una superficie suave y lisa y un brillo intenso brillante * Renueva los tratamientos de cera existentes y deja un efecto adicional [&hellip;]<\/p>\n","protected":false},"featured_media":3662,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[82,23],"product_tag":[74],"_links":{"self":[{"href":"https:\/\/texsalvenezuela.com\/tienda\/wp-json\/wp\/v2\/product\/4229"}],"collection":[{"href":"https:\/\/texsalvenezuela.com\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/texsalvenezuela.com\/tienda\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/texsalvenezuela.com\/tienda\/wp-json\/wp\/v2\/comments?post=4229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/texsalvenezuela.com\/tienda\/wp-json\/wp\/v2\/media\/3662"}],"wp:attachment":[{"href":"https:\/\/texsalvenezuela.com\/tienda\/wp-json\/wp\/v2\/media?parent=4229"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/texsalvenezuela.com\/tienda\/wp-json\/wp\/v2\/product_cat?post=4229"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/texsalvenezuela.com\/tienda\/wp-json\/wp\/v2\/product_tag?post=4229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}